{"id":2232,"date":"2026-01-08T09:36:23","date_gmt":"2026-01-08T09:36:23","guid":{"rendered":"https:\/\/onechurch.de\/datenschutzerklaerung\/"},"modified":"2026-01-08T09:36:23","modified_gmt":"2026-01-08T09:36:23","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/onechurch.de\/pt\/datenschutzerklaerung\/","title":{"rendered":"Declara\u00e7\u00e3o de prote\u00e7\u00e3o de dados"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-impressum-template","meta":{"saved_in_kubio":true,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"class_list":["post-2232","page","type-page","status-publish","hentry"],"kubio_ai_page_context":{"short_desc":"","purpose":"general"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutzerkl\u00e4rung - Website One Church<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onechurch.de\/pt\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Website One Church\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onechurch.de\/pt\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Website One Church\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/datenschutzerklaerung\\\/\",\"url\":\"https:\\\/\\\/onechurch.de\\\/datenschutzerklaerung\\\/\",\"name\":\"Datenschutzerkl\u00e4rung - Website One Church\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#website\"},\"datePublished\":\"2026-01-08T09:36:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/datenschutzerklaerung\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onechurch.de\\\/datenschutzerklaerung\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/datenschutzerklaerung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/onechurch.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#website\",\"url\":\"https:\\\/\\\/onechurch.de\\\/\",\"name\":\"One Church Hagen\",\"description\":\"Website der One Church\",\"publisher\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onechurch.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#organization\",\"name\":\"One Church Hagen\",\"url\":\"https:\\\/\\\/onechurch.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onechurch.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/OCH_Logo_4c_Quer.png\",\"contentUrl\":\"https:\\\/\\\/onechurch.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/OCH_Logo_4c_Quer.png\",\"width\":1500,\"height\":455,\"caption\":\"One Church Hagen\"},\"image\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Website One Church","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onechurch.de\/pt\/datenschutzerklaerung\/","og_locale":"pt_PT","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Website One Church","og_url":"https:\/\/onechurch.de\/pt\/datenschutzerklaerung\/","og_site_name":"Website One Church","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onechurch.de\/datenschutzerklaerung\/","url":"https:\/\/onechurch.de\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Website One Church","isPartOf":{"@id":"https:\/\/onechurch.de\/#website"},"datePublished":"2026-01-08T09:36:23+00:00","breadcrumb":{"@id":"https:\/\/onechurch.de\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onechurch.de\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/onechurch.de\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/onechurch.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/onechurch.de\/#website","url":"https:\/\/onechurch.de\/","name":"One Church Hagen","description":"Website der One Church","publisher":{"@id":"https:\/\/onechurch.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onechurch.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/onechurch.de\/#organization","name":"One Church Hagen","url":"https:\/\/onechurch.de\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/onechurch.de\/#\/schema\/logo\/image\/","url":"https:\/\/onechurch.de\/wp-content\/uploads\/2025\/09\/OCH_Logo_4c_Quer.png","contentUrl":"https:\/\/onechurch.de\/wp-content\/uploads\/2025\/09\/OCH_Logo_4c_Quer.png","width":1500,"height":455,"caption":"One Church Hagen"},"image":{"@id":"https:\/\/onechurch.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":0,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages\/2232\/revisions"}],"wp:attachment":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/media?parent=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}