{"id":658,"date":"2025-09-16T09:24:27","date_gmt":"2025-09-16T09:24:27","guid":{"rendered":"https:\/\/onechurch.de\/spenden\/"},"modified":"2025-11-19T12:58:02","modified_gmt":"2025-11-19T12:58:02","slug":"spenden","status":"publish","type":"page","link":"https:\/\/onechurch.de\/pt\/spenden\/","title":{"rendered":"Doa\u00e7\u00f5es"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-header-unterseiten-2","meta":{"saved_in_kubio":true,"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"footnotes":""},"class_list":["post-658","page","type-page","status-publish","hentry"],"kubio_ai_page_context":{"short_desc":"","purpose":"general"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spenden - ONE Church Hagen<\/title>\n<meta name=\"description\" content=\"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onechurch.de\/pt\/spenden\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spenden - ONE Church Hagen\" \/>\n<meta property=\"og:description\" content=\"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onechurch.de\/pt\/spenden\/\" \/>\n<meta property=\"og:site_name\" content=\"Website One Church\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-19T12:58:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/spenden\\\/\",\"url\":\"https:\\\/\\\/onechurch.de\\\/spenden\\\/\",\"name\":\"Spenden - ONE Church Hagen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#website\"},\"datePublished\":\"2025-09-16T09:24:27+00:00\",\"dateModified\":\"2025-11-19T12:58:02+00:00\",\"description\":\"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/spenden\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onechurch.de\\\/spenden\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/spenden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/onechurch.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spenden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#website\",\"url\":\"https:\\\/\\\/onechurch.de\\\/\",\"name\":\"One Church Hagen\",\"description\":\"Website der One Church\",\"publisher\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onechurch.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#organization\",\"name\":\"One Church Hagen\",\"url\":\"https:\\\/\\\/onechurch.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/onechurch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/onechurch.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/OCH_Logo_4c_Quer.png\",\"contentUrl\":\"https:\\\/\\\/onechurch.de\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/OCH_Logo_4c_Quer.png\",\"width\":1500,\"height\":455,\"caption\":\"One Church Hagen\"},\"image\":{\"@id\":\"https:\\\/\\\/onechurch.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spenden - ONE Church Hagen","description":"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onechurch.de\/pt\/spenden\/","og_locale":"pt_PT","og_type":"article","og_title":"Spenden - ONE Church Hagen","og_description":"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.","og_url":"https:\/\/onechurch.de\/pt\/spenden\/","og_site_name":"Website One Church","article_modified_time":"2025-11-19T12:58:02+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/onechurch.de\/spenden\/","url":"https:\/\/onechurch.de\/spenden\/","name":"Spenden - ONE Church Hagen","isPartOf":{"@id":"https:\/\/onechurch.de\/#website"},"datePublished":"2025-09-16T09:24:27+00:00","dateModified":"2025-11-19T12:58:02+00:00","description":"Unterst\u00fctze die ONE Church Hagen mit deiner Spende. Durch viele gro\u00dfz\u00fcgige Menschen werden die Angebote der ONE Church Hagen finanziert.","breadcrumb":{"@id":"https:\/\/onechurch.de\/spenden\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onechurch.de\/spenden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/onechurch.de\/spenden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/onechurch.de\/"},{"@type":"ListItem","position":2,"name":"Spenden"}]},{"@type":"WebSite","@id":"https:\/\/onechurch.de\/#website","url":"https:\/\/onechurch.de\/","name":"One Church Hagen","description":"Website der One Church","publisher":{"@id":"https:\/\/onechurch.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onechurch.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/onechurch.de\/#organization","name":"One Church Hagen","url":"https:\/\/onechurch.de\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/onechurch.de\/#\/schema\/logo\/image\/","url":"https:\/\/onechurch.de\/wp-content\/uploads\/2025\/09\/OCH_Logo_4c_Quer.png","contentUrl":"https:\/\/onechurch.de\/wp-content\/uploads\/2025\/09\/OCH_Logo_4c_Quer.png","width":1500,"height":455,"caption":"One Church Hagen"},"image":{"@id":"https:\/\/onechurch.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages\/658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/comments?post=658"}],"version-history":[{"count":1,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages\/658\/revisions"}],"predecessor-version":[{"id":798,"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/pages\/658\/revisions\/798"}],"wp:attachment":[{"href":"https:\/\/onechurch.de\/pt\/wp-json\/wp\/v2\/media?parent=658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}